{"id":6446,"date":"2013-09-04T08:07:27","date_gmt":"2013-09-04T05:07:27","guid":{"rendered":"https:\/\/ambsofia.esteri.it\/news\/dall_ambasciata\/2013\/09\/news-20130823-erp\/"},"modified":"2013-09-04T08:07:27","modified_gmt":"2013-09-04T05:07:27","slug":"news-20130823-erp","status":"publish","type":"post","link":"https:\/\/ambsofia.esteri.it\/it\/news\/dall_ambasciata\/2013\/09\/news-20130823-erp\/","title":{"rendered":"COMUNE DI SORRADILE (OR) &#8211; PUBBLICITA&#8217; BANDO DI CONCORSO PER L&#8217;ASSEGNAZIONE DI ALLOGGI E.R.P."},"content":{"rendered":"<p><P>Il Comune di Sorradile (OR), rende nota &#8211; con il bando in data 13 agosto 2013 &#8211; l&#8217;indizione di un concorso per l&#8217;assegnazione di alloggi di edilizia residenziale pubblica in tale Comune. Le domande di partecipazione devono essere presentate entro 30 giorni dalla data di pubblicazione del bando sul B.U.R.A.S.; per i lavoratori emigrati all&#8217;estero i termini sono prorogati di 60 giorni per i residenti nell&#8217;area europea e di 90 giorni per i residenti in Paesi extraeuropei.<BR><BR>Gli eventuali interessati potrenno rivolgersi direttamente al predetto Comune al seguente indirizzo:<BR>Comune di Sorradile<BR>Corso Umberto I, n.61<BR>09080 SORRADILE (OR)<BR>Sito web: <A href=\"http:\/\/www.comune.sorradile.or.it\">www.comune.sorradile.or.it<\/A><BR>e-mail: <A href=\"mailto:comune.sorradile@tiscali.it\">comune.sorradile@tiscali.it<\/A><BR><BR><\/P><P>\u00a0<\/P><\/p>\n","protected":false},"excerpt":{"rendered":"Il Comune di Sorradile (OR), rende nota &#8211; con il bando in data 13 agosto 2013 &#8211; l&#8217;indizione di un concorso per l&#8217;assegnazione di alloggi di edilizia residenziale pubblica in tale Comune. Le domande di partecipazione devono essere presentate entro 30 giorni dalla data di pubblicazione del bando sul B.U.R.A.S.; per i lavoratori emigrati all&#8217;estero [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-6446","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/posts\/6446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=6446"}],"version-history":[{"count":0,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/posts\/6446\/revisions"}],"wp:attachment":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=6446"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=6446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}