{"id":6234,"date":"2015-10-06T07:12:38","date_gmt":"2015-10-06T04:12:38","guid":{"rendered":"https:\/\/ambsofia.esteri.it\/news\/dall_ambasciata\/2015\/10\/ploaghe\/"},"modified":"2015-10-06T07:12:38","modified_gmt":"2015-10-06T04:12:38","slug":"ploaghe","status":"publish","type":"post","link":"https:\/\/ambsofia.esteri.it\/it\/news\/dall_ambasciata\/2015\/10\/ploaghe\/","title":{"rendered":"COMUNE DI PLOAGHE (SS) &#8211; PUBBLICITA&#8217; BANDO DI CONCORSO PER L&#8217;ASSEGNAZIONE DI\u00a0 ALLOGGI POPOLARI DI E.R.P"},"content":{"rendered":"<p>Il Comune di Ploaghe (SS) ha reso noto &#8211; con bando in data 17 settembre 2015 &#8211;<BR>l&#8217;indizione di un concorso per l&#8217;assegnazione di alloggi a canone sostenibile. Le<BR>domande dovranno essere inviate per posta raccomandata A\/R al seguente indirizzo:<BR>&#8211; Comune di Ploaghe &#8211; Ufficio Tecnico &#8211; Piazza S. Pietro n. 1 &#8211; Ploaghe (SS) &#8211; Tel.<BR>079\/4479913 &#8211; Fax 079\/4479927 (<A href=\"http:\/\/www.comune.ploaghe.ss.it\">www.comune.ploaghe.ss.it<\/A>) &#8211; (e-mail:<BR><A href=\"mailto:responsabiletecnico@comune.ploaghe.ss.it\">responsabiletecnico@comune.ploaghe.ss.it<\/A>).<BR>Le scadenze per la presentazione delle domande sono di 30 giorni dalla data di<BR>pubblicazione del bando ossia entro il 17\/10\/2015.<BR>Per i lavoratori emigrati all&#8217;estero i termini sono cosi&#8217; prorogati:<BR>&#8211; 60 giorni ovvero entro il 16\/11\/2015 per i residenti nell&#8217;area europea<BR>&#8211; 90 giorni ossia entro il 16\/12\/2015 per i residenti nei paesi extraeurope<\/p>\n","protected":false},"excerpt":{"rendered":"Il Comune di Ploaghe (SS) ha reso noto &#8211; con bando in data 17 settembre 2015 &#8211;l&#8217;indizione di un concorso per l&#8217;assegnazione di alloggi a canone sostenibile. Ledomande dovranno essere inviate per posta raccomandata A\/R al seguente indirizzo:&#8211; Comune di Ploaghe &#8211; Ufficio Tecnico &#8211; Piazza S. Pietro n. 1 &#8211; Ploaghe (SS) &#8211; Tel.079\/4479913 [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-6234","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/posts\/6234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=6234"}],"version-history":[{"count":0,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/posts\/6234\/revisions"}],"wp:attachment":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=6234"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=6234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}