{"id":6119,"date":"2016-04-01T12:44:12","date_gmt":"2016-04-01T09:44:12","guid":{"rendered":"https:\/\/ambsofia.esteri.it\/news\/dall_ambasciata\/2016\/04\/bando-alloggi-popolari-comune-di-acireale-catania\/"},"modified":"2016-04-01T12:44:12","modified_gmt":"2016-04-01T09:44:12","slug":"bando-alloggi-popolari-comune-di-acireale-catania","status":"publish","type":"post","link":"https:\/\/ambsofia.esteri.it\/it\/news\/dall_ambasciata\/2016\/04\/bando-alloggi-popolari-comune-di-acireale-catania\/","title":{"rendered":"COMUNE DI ACIREALE (CT) &#8211; PUBBLICITA&#8217; BANDO DI CONCORSO PER L&#8217;ASSEGNAZIONE DI ALLOGGI POPOLARI DI E.R.P"},"content":{"rendered":"<p><P>Il Comune di Acireale (CT) ha reso noto &#8211; con bando in data 8 marzo 2016 &#8211; l&#8217;indizione di un concorso per l&#8217;assegnazione di alloggi di edilizia residenziale pubblica. Le domande dovranno essere inviate per posta raccomandata A\/R al seguente indirizzo: &#8211; Comune di Acireale &#8211; Via Degli Ulivi n. 21 &#8211; Acireale (CT) &#8211; Tel. 095\/895721-33 &#8211; Fax 095\/895748 (<A href=\"http:\/\/www.comune.acireale.ct.it\">www.comune.acireale.ct.it<\/A>). Le scadenze per la presentazione delle domande sono di 60 giorni dalla data di pubblicazione del bando. <BR><\/P><P>Per i lavoratori emigrati all&#8217;estero i termini sono cosi&#8217; prorogati: <BR><\/P><br \/>\n<P>&#8211; 60 giorni per i residenti nell&#8217;area europea <BR>&#8211; 120 giorni per i residenti nei paesi extraeuropei <BR><\/P><\/p>\n","protected":false},"excerpt":{"rendered":"Il Comune di Acireale (CT) ha reso noto &#8211; con bando in data 8 marzo 2016 &#8211; l&#8217;indizione di un concorso per l&#8217;assegnazione di alloggi di edilizia residenziale pubblica. Le domande dovranno essere inviate per posta raccomandata A\/R al seguente indirizzo: &#8211; Comune di Acireale &#8211; Via Degli Ulivi n. 21 &#8211; Acireale (CT) &#8211; [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-6119","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/posts\/6119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=6119"}],"version-history":[{"count":0,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/posts\/6119\/revisions"}],"wp:attachment":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=6119"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=6119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}