{"id":6113,"date":"2016-04-08T06:46:37","date_gmt":"2016-04-08T03:46:37","guid":{"rendered":"https:\/\/ambsofia.esteri.it\/news\/dall_ambasciata\/2016\/04\/elezioni-amministrative-2016-nella-regione-siciliana-2\/"},"modified":"2016-04-08T06:46:37","modified_gmt":"2016-04-08T03:46:37","slug":"elezioni-amministrative-2016-nella-regione-siciliana-2","status":"publish","type":"post","link":"https:\/\/ambsofia.esteri.it\/it\/news\/dall_ambasciata\/2016\/04\/elezioni-amministrative-2016-nella-regione-siciliana-2\/","title":{"rendered":"ELEZIONI AMMINISTRATIVE 2016 NELLA REGIONE SICILIANA. AGEVOLAZIONI DI VIAGGIO IN FAVORE DEGLI ELETTORI RESIDENTI ALL&#8217;ESTERO"},"content":{"rendered":"<p><P>Si rende noto che la Regione Siciliana\u00a0ha emanato il\u00a0Decreto Assessoriale n. 26 del 04\/04\/2016 con il quale sono state fissate le elezioni dei Sindaci e dei Consigli comunali di cui all&#8217;elenco allegato al Decreto medesimo (<A href=\"\/resource\/2016\/04\/96474_f_amb61Nota_Regione_Siciliana_prot_4711_del_642016.pdf\">Scarica Decreto Assessoriale n. 26 &#8211; ><\/A>)<\/P><P>Le elezioni &#8211; per le quali sono previste agevolazioni di viaggio per gli elettori residenti all&#8217;estero &#8211; avranno luogo il 05 giugno 2016. <BR>Limitatamente alle elezioni dei Sindaci, inoltre, un eventuale secondo turno avra&#8217; luogo nella giornata del 19 giugno. <BR><\/P><\/p>\n","protected":false},"excerpt":{"rendered":"Si rende noto che la Regione Siciliana\u00a0ha emanato il\u00a0Decreto Assessoriale n. 26 del 04\/04\/2016 con il quale sono state fissate le elezioni dei Sindaci e dei Consigli comunali di cui all&#8217;elenco allegato al Decreto medesimo (Scarica Decreto Assessoriale n. 26 &#8211; >)Le elezioni &#8211; per le quali sono previste agevolazioni di viaggio per gli elettori [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-6113","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/posts\/6113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=6113"}],"version-history":[{"count":0,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/posts\/6113\/revisions"}],"wp:attachment":[{"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=6113"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambsofia.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=6113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}